{"id":1266,"date":"2025-08-22T11:59:51","date_gmt":"2025-08-22T09:59:51","guid":{"rendered":"https:\/\/ocdsavila2026.com\/ocds\/"},"modified":"2025-12-11T00:01:13","modified_gmt":"2025-12-10T23:01:13","slug":"ocds","status":"publish","type":"page","link":"https:\/\/ocdsavila2026.com\/fr\/ocds\/","title":{"rendered":"OCDS"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1><span>L'OCDS<\/span><\/h1>\n<p>&nbsp;<\/p>\n<p>La grande famille du Carmel th\u00e9r\u00e9sien est pr\u00e9sente dans le monde de multiples fa\u00e7ons. Son noyau est l'Ordre des Carmes d\u00e9chauss\u00e9s, compos\u00e9 de fr\u00e8res, de religieuses clo\u00eetr\u00e9es et de la\u00efcs (OCDS). C'est un Ordre avec le m\u00eame charisme. Elle se nourrit de la longue tradition historique du Carmel, contenue dans la R\u00e8gle de saint Albert et dans l'enseignement des docteurs de l'\u00c9glise carm\u00e9lites et d'autres saints de l'Ordre.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Les Carmes s\u00e9culiers, les Fr\u00e8res et les Moniales sont les fils et les filles de l'Ordre de Notre-Dame du Mont Carmel et de Sainte Th\u00e9r\u00e8se de J\u00e9sus. Ils partagent donc avec les religieux le m\u00eame charisme, chacun le vivant selon son propre \u00e9tat de vie. C'est une seule famille avec les m\u00eames biens spirituels, la m\u00eame vocation \u00e0 la saintet\u00e9 et la m\u00eame mission apostolique. Les la\u00efcs apportent \u00e0 l'Ordre la richesse de sa s\u00e9cularit\u00e9.   <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Les membres de l'Ordre S\u00e9culier des Carmes D\u00e9chauss\u00e9s sont des fid\u00e8les de l'Eglise appel\u00e9s \u00e0 vivre \"dans le don de J\u00e9sus-Christ\" \u00e0 travers \"l'amiti\u00e9 avec Celui dont nous savons qu'il nous aime\", en servant l'Eglise. Sous la protection de Notre-Dame du Mont Carmel, selon l'inspiration de sainte Th\u00e9r\u00e8se de J\u00e9sus, de saint Jean de la Croix et de la tradition biblique du proph\u00e8te \u00c9lie, ils cherchent \u00e0 approfondir l'engagement chr\u00e9tien re\u00e7u au bapt\u00eame. <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"chroniques\" class=\"et_d4_element et_pb_section et_pb_section_2 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_pb_top_divider et_block_section\" >\n\t\t\t\t<div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_3 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>La Vierge Marie est pr\u00e9sente de mani\u00e8re particuli\u00e8re, notamment comme mod\u00e8le de fid\u00e9lit\u00e9 dans l'\u00e9coute du Seigneur et dans son attitude de service envers Lui et envers les autres. Marie est celle qui a gard\u00e9 et m\u00e9dit\u00e9 dans son c\u0153ur la vie et les actions de son Fils\", donnant ainsi l'exemple de la contemplation. Marie est un exemple de service apostolique. Et c'est encore elle qui a attendu la venue de l'Esprit Saint, pers\u00e9v\u00e9rant dans la pri\u00e8re avec les ap\u00f4tres, t\u00e9moignant de la pri\u00e8re d'intercession. Elle est la M\u00e8re de l'Ordre. Le carme s\u00e9culier jouit de sa protection sp\u00e9ciale et cultive une sinc\u00e8re d\u00e9votion mariale.     <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_3 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_pb_top_divider et_block_section\" >\n\t\t\t\t<div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_4  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\" data-et-multi-view=\"{&quot;schema&quot;:{&quot;content&quot;:{&quot;desktop&quot;:&quot;&lt;p&gt;&nbsp;&lt;\\\/p&gt;\\n&lt;p&gt;Le proph\\u00e8te \\u00c9lie repr\\u00e9sente la tradition du Carmel et est l&#039;inspiration pour vivre en pr\\u00e9sence de Dieu, en le cherchant dans la solitude et le silence avec z\\u00e8le pour la gloire de Dieu. Le S\\u00e9culier vit la dimension proph\\u00e9tique de la vie chr\\u00e9tienne et de la spiritualit\\u00e9 carm\\u00e9litaine en promouvant la loi d&#039;amour et de v\\u00e9rit\\u00e9 de Dieu dans le monde et surtout en devenant la voix de ceux qui ne peuvent exprimer par eux-m\\u00eames cet amour et cette v\\u00e9rit\\u00e9.&lt;br \\\/&gt;La R\\u00e8gle de Saint-Albert est l&#039;expression originale de la spiritualit\\u00e9 carm\\u00e9litaine. Il a \\u00e9t\\u00e9 \\u00e9crit pour les la\\u00efcs qui se sont rassembl\\u00e9s sur le Mont Carmel pour vivre une vie consacr\\u00e9e \\u00e0 la m\\u00e9ditation de la Parole de Dieu sous la protection de Notre Dame.&lt;br \\\/&gt;La suite de J\\u00e9sus en tant que membres de l&#039;Ordre S\\u00e9culier est exprim\\u00e9e par la promesse de s&#039;efforcer \\u00e0 la perfection \\u00e9vang\\u00e9lique dans l&#039;esprit des conseils \\u00e9vang\\u00e9liques de chastet\\u00e9, de pauvret\\u00e9 et d&#039;ob\\u00e9issance et des B\\u00e9atitudes.  &lt;\\\/p&gt;&quot;,&quot;tablet&quot;:&quot;&lt;p&gt; &lt;\\\/p&gt;\\n&lt;p&gt;El Profeta El\\u00edas representa la tradici\\u00f3n del Carmelo y es el inspirador para vivir en la presencia de Dios, busc\\u00e1ndolo en la soledad y el silencio con celo por la gloria Dios. El Seglar vive la dimensi\\u00f3n prof\\u00e9tica de la vida cristiana y de la espiritualidad carmelitana promoviendo la ley de Dios de amor y de verdad en el mundo y especialmente haci\\u00e9ndose voz de aquellos que no pueden por s\\u00ed mismos expresar este amor y esta verdad.&lt;br \\\/&gt;La Regla de San Alberto es la expresi\\u00f3n original de la espiritualidad del Carmelo. Fue escrita para laicos que se reunieron en el Monte Carmelo para vivir una vida dedicada a la meditaci\\u00f3n de la Palabra de Dios bajo la protecci\\u00f3n de la Virgen.&lt;br \\\/&gt;El seguimiento de Jes\\u00fas como miembros de la Orden Seglar se expresa a trav\\u00e9s de la promesa de tender a la perfecci\\u00f3n evang\\u00e9lica en el esp\\u00edritu de los consejos evang\\u00e9licos de castidad, pobreza y obediencia y de las Bienaventuranzas.&lt;\\\/p&gt;&quot;},&quot;target&quot;:&quot;&quot;,&quot;hover_selector&quot;:&quot;&quot;},&quot;slug&quot;:&quot;et_pb_text&quot;}\" data-et-multi-view-load-tablet-hidden=\"true\"><p>&nbsp;<\/p>\n<p>Le proph\u00e8te \u00c9lie repr\u00e9sente la tradition du Carmel et est l'inspiration pour vivre en pr\u00e9sence de Dieu, en le cherchant dans la solitude et le silence avec z\u00e8le pour la gloire de Dieu. Le S\u00e9culier vit la dimension proph\u00e9tique de la vie chr\u00e9tienne et de la spiritualit\u00e9 carm\u00e9litaine en promouvant la loi d'amour et de v\u00e9rit\u00e9 de Dieu dans le monde et surtout en devenant la voix de ceux qui ne peuvent exprimer par eux-m\u00eames cet amour et cette v\u00e9rit\u00e9.<br \/>La R\u00e8gle de Saint-Albert est l'expression originale de la spiritualit\u00e9 carm\u00e9litaine. Il a \u00e9t\u00e9 \u00e9crit pour les la\u00efcs qui se sont rassembl\u00e9s sur le Mont Carmel pour vivre une vie consacr\u00e9e \u00e0 la m\u00e9ditation de la Parole de Dieu sous la protection de Notre Dame.<br \/>La suite de J\u00e9sus en tant que membres de l'Ordre S\u00e9culier est exprim\u00e9e par la promesse de s'efforcer \u00e0 la perfection \u00e9vang\u00e9lique dans l'esprit des conseils \u00e9vang\u00e9liques de chastet\u00e9, de pauvret\u00e9 et d'ob\u00e9issance et des B\u00e9atitudes.  <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_7  et_pb_css_mix_blend_mode et-last-child et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_4  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_2_3 et_pb_column et_pb_column_8  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_5  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>La vocation du carmel th\u00e9r\u00e9sien est un engagement \u00e0 \"vivre dans l'ob\u00e9issance \u00e0 J\u00e9sus-Christ\", \"en m\u00e9ditant jour et nuit la loi du Seigneur et en veillant dans la pri\u00e8re\". Fid\u00e8le \u00e0 ce principe de la R\u00e8gle, sainte Th\u00e9r\u00e8se a fait de la pri\u00e8re le fondement et l'exercice premier de sa famille religieuse. C'est pourquoi le la\u00efc est appel\u00e9 \u00e0 faire en sorte que la pri\u00e8re impr\u00e8gne toute son existence, afin de marcher en pr\u00e9sence du Dieu vivant (cf. 1 R 18, 14), par l'exercice constant de la foi, de l'esp\u00e9rance et de l'amour, de sorte que toute sa vie soit une pri\u00e8re, une recherche de l'union avec Dieu. L'objectif sera d'int\u00e9grer l'exp\u00e9rience de Dieu \u00e0 l'exp\u00e9rience de la vie : \u00eatre contemplatif dans la pri\u00e8re et dans l'accomplissement de sa mission. Par cons\u00e9quent, le la\u00efc s'engagera \u00e0 consacrer du temps chaque jour \u00e0 la pratique de l'oraison mentale. C'est le moment d'\u00eatre avec Dieu et de renforcer la relation avec Lui afin d'\u00eatre de v\u00e9ritables t\u00e9moins de sa pr\u00e9sence dans le monde.    <\/p>\n<p>Tout cela est v\u00e9cu en communaut\u00e9, ce qui aide la carm\u00e9lite s\u00e9culi\u00e8re \u00e0 grandir spirituellement et la forme dans l'\u00e9tude de Notre Sainte M\u00e8re Th\u00e9r\u00e8se de J\u00e9sus, Notre Saint P\u00e8re Jean de la Croix, Sainte Th\u00e9r\u00e8se de l'Enfant J\u00e9sus et d'autres saints carm\u00e9lites.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_9  et_pb_css_mix_blend_mode et-last-child et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1266","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OCDS - OCDS 2026<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocdsavila2026.com\/fr\/ocds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OCDS - OCDS 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocdsavila2026.com\/fr\/ocds\/\" \/>\n<meta property=\"og:site_name\" content=\"OCDS 2026\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T23:01:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/ocds\\\/\",\"url\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/ocds\\\/\",\"name\":\"OCDS - OCDS 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-08-22T09:59:51+00:00\",\"dateModified\":\"2025-12-10T23:01:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/ocds\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/ocds\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/ocds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OCDS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/\",\"name\":\"OCDS 2026\",\"description\":\"Encuentro Mundial OCDS 2026\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#organization\",\"name\":\"Carmelitas descalzos\",\"url\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ocdsavila2026.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoiberica-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/ocdsavila2026.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoiberica-scaled-1.png\",\"width\":2560,\"height\":2560,\"caption\":\"Carmelitas descalzos\"},\"image\":{\"@id\":\"https:\\\/\\\/ocdsavila2026.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OCDS - OCDS 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocdsavila2026.com\/fr\/ocds\/","og_locale":"fr_FR","og_type":"article","og_title":"OCDS - OCDS 2026","og_url":"https:\/\/ocdsavila2026.com\/fr\/ocds\/","og_site_name":"OCDS 2026","article_modified_time":"2025-12-10T23:01:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ocdsavila2026.com\/fr\/ocds\/","url":"https:\/\/ocdsavila2026.com\/fr\/ocds\/","name":"OCDS - OCDS 2026","isPartOf":{"@id":"https:\/\/ocdsavila2026.com\/fr\/#website"},"datePublished":"2025-08-22T09:59:51+00:00","dateModified":"2025-12-10T23:01:13+00:00","breadcrumb":{"@id":"https:\/\/ocdsavila2026.com\/fr\/ocds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocdsavila2026.com\/fr\/ocds\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ocdsavila2026.com\/fr\/ocds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ocdsavila2026.com\/fr\/"},{"@type":"ListItem","position":2,"name":"OCDS"}]},{"@type":"WebSite","@id":"https:\/\/ocdsavila2026.com\/fr\/#website","url":"https:\/\/ocdsavila2026.com\/fr\/","name":"OCDS 2026","description":"Encuentro Mundial OCDS 2026","publisher":{"@id":"https:\/\/ocdsavila2026.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocdsavila2026.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ocdsavila2026.com\/fr\/#organization","name":"Carmelitas descalzos","url":"https:\/\/ocdsavila2026.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ocdsavila2026.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ocdsavila2026.com\/wp-content\/uploads\/2026\/01\/logoiberica-scaled-1.png","contentUrl":"https:\/\/ocdsavila2026.com\/wp-content\/uploads\/2026\/01\/logoiberica-scaled-1.png","width":2560,"height":2560,"caption":"Carmelitas descalzos"},"image":{"@id":"https:\/\/ocdsavila2026.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/pages\/1266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/comments?post=1266"}],"version-history":[{"count":13,"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/pages\/1266\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/pages\/1266\/revisions\/3117"}],"wp:attachment":[{"href":"https:\/\/ocdsavila2026.com\/fr\/wp-json\/wp\/v2\/media?parent=1266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}